{"id":45,"date":"2025-04-16T15:53:37","date_gmt":"2025-04-16T13:53:37","guid":{"rendered":"https:\/\/csi.advmedialab.com\/?page_id=45"},"modified":"2025-10-01T12:28:40","modified_gmt":"2025-10-01T10:28:40","slug":"esperienze-it","status":"publish","type":"page","link":"https:\/\/www.centrostuditaliani.org\/it\/esperienze-it\/","title":{"rendered":"Esperienze"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;647&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; color_overlay=&#8221;rgba(0,0,0,0.6)&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column top_padding_desktop=&#8221;32%&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;32%&#8221; top_padding_tablet=&#8221;44%&#8221; constrain_group_102=&#8221;yes&#8221; bottom_padding_tablet=&#8221;44%&#8221; top_padding_phone=&#8221;44%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;44%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;center&#8221; phone_text_alignment=&#8221;center&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-lg-offset-2 vc_col-lg-8 vc_col-md-offset-2 vc_col-md-8&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h1>Esperienze al 100% italiane<\/h1>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;80px&#8221; bottom_padding=&#8221;40px&#8221; left_padding_desktop=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5%&#8221; top_padding_tablet=&#8221;56px&#8221; bottom_padding_tablet=&#8221;24px&#8221; top_padding_phone=&#8221;56px&#8221; bottom_padding_phone=&#8221;24px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column constrain_group_100=&#8221;yes&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-lg-offset-1 vc_col-lg-10 vc_col-md-offset-1 vc_col-md-10 vc_col-sm-offset-0&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Autenticit\u00e0 al 100%. Questo \u00e8 il cuore di Vera Italia. Vogliamo farti vivere delle esperienze indimenticabili!<\/p>\n<p>Ci impegniamo a offrire esperienze italiane indimenticabili, che spaziano dai momenti quotidiani pi\u00f9 semplici a quelli grandiosi e mozzafiato. Crediamo che imparare una lingua significhi anche <strong>immergersi nella cultura e nello stile di vita<\/strong> dei suoi parlanti nativi.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;24px&#8221; bottom_padding_tablet=&#8221;24px&#8221; bottom_padding_phone=&#8221;24px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-lg-offset-4 vc_col-md-offset-4&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Cosa troverai in questa pagina<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #4d5765;color:#4d5765\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #4d5765;color:#4d5765\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.centrostuditaliani.org\/it\/esperienze-it\/#Vivi_unesperienza_100_italiana_mentre_impari_litaliano\" >Vivi un&#8217;esperienza 100% italiana mentre impari l&#8217;italiano<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.centrostuditaliani.org\/it\/esperienze-it\/#Corsi_di_arte_e_cultura\" >Corsi di arte e cultura<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.centrostuditaliani.org\/it\/esperienze-it\/#Esperienze_enogastronomiche\" >Esperienze enogastronomiche<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.centrostuditaliani.org\/it\/esperienze-it\/#Scopri_lItalia\" >Scopri l&#8217;Italia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.centrostuditaliani.org\/it\/esperienze-it\/#Goditi_la_musica\" >Goditi la musica<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.centrostuditaliani.org\/it\/esperienze-it\/#In_quali_citta_puoi_imparare_litaliano\" >In quali citt\u00e0 puoi imparare l&#8217;italiano?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.centrostuditaliani.org\/it\/esperienze-it\/#Hai_bisogno_di_prepararti_per_un_esame_Scopri_i_nostri_corsi\" >Hai bisogno di prepararti per un esame? Scopri i nostri corsi!<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;5101&#8243; background_image_position=&#8221;center center&#8221; background_image_stacking=&#8221;default&#8221; background_image_loading=&#8221;default&#8221; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;20px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; color_overlay=&#8221;rgba(0,0,0,0.3)&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;60vh&#8221; custom_height_phone=&#8221;400px&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;80px&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;80px&#8221; left_padding_desktop=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5%&#8221; top_padding_tablet=&#8221;56px&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;56px&#8221; top_padding_phone=&#8221;56px&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;56px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column constrain_group_100=&#8221;yes&#8221; constrain_group_102=&#8221;yes&#8221; constrain_group_104=&#8221;yes&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-lg-offset-1 vc_col-lg-10 vc_col-md-offset-1 vc_col-md-10 vc_col-sm-offset-0&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2><span class=\"ez-toc-section\" id=\"Vivi_unesperienza_100_italiana_mentre_impari_litaliano\"><\/span>Vivi un&#8217;esperienza 100% italiana mentre impari l&#8217;italiano<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Scopri il patrimonio storico, culturale, naturalistico e gastronomico del nostro Bel Paese attraverso le attivit\u00e0 e le escursioni proposte da Centro Studi Italiani. Impara la lingua italiana <strong>esplorando i segreti del nostro territorio<\/strong> e i sapori delle nostre regioni. Tour guidati, escursioni, esperienze enogastronomiche, corsi di musica, d\u2019arte e ceramica ti aspettano in ogni stagione! Scopri tutte le nostre proposte![\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;56px&#8221; bottom_padding=&#8221;80px&#8221; left_padding_desktop=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5%&#8221; top_padding_tablet=&#8221;56px&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;56px&#8221; top_padding_phone=&#8221;56px&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;56px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-lg-6 vc_col-md-6&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;h3-green&#8221;]\n<h3><span class=\"ez-toc-section\" id=\"Corsi_di_arte_e_cultura\"><\/span>Corsi di arte e cultura<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Scopri il cuore dell\u2019Italia attraverso la nostra ampia gamma di attivit\u00e0 culturali e laboratori. Non si tratta solo di visite turistiche passive, ma di un <strong>coinvolgimento attivo nelle tradizioni e nelle passioni<\/strong> che rendono l\u2019Italia unica.[\/vc_column_text][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;default_arrow&#8221; text=&#8221;Scopri di pi\u00f9&#8221; url=&#8221;https:\/\/www.centrostuditaliani.org\/corsi\/arte-e-cultura\/&#8221; margin_top=&#8221;24px&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin_tablet=&#8221;56px&#8221; top_margin_phone=&#8221;56px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;right&#8221; tablet_text_alignment=&#8221;left&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-lg-offset-1 vc_col-lg-5 vc_col-md-offset-1 vc_col-md-5&#8243;][image_with_animation image_url=&#8221;4545&#8243; image_size=&#8221;regular&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;15px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; bg_color=&#8221;#e3f5ea&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;80px&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;80px&#8221; left_padding_desktop=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5%&#8221; top_padding_tablet=&#8221;56px&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;56px&#8221; top_padding_phone=&#8221;56px&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;56px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin_tablet=&#8221;56px&#8221; top_margin_phone=&#8221;56px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;left&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-lg-offset-0 vc_col-lg-5 vc_col-md-offset-0 vc_col-md-5&#8243;][image_with_animation image_url=&#8221;4549&#8243; image_size=&#8221;regular&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;15px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-lg-offset-1 vc_col-lg-6 vc_col-md-offset-1 vc_col-md-6 vc_col-sm-offset-0&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;h3-green&#8221;]\n<h3><span class=\"ez-toc-section\" id=\"Esperienze_enogastronomiche\"><\/span>Esperienze enogastronomiche<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Vivi esperienze enogastronomiche incredibili! Sappiamo che l\u2019apprendimento della lingua \u00e8 pi\u00f9 efficace quando si intreccia con l\u2019immersione culturale, e non c\u2019\u00e8 modo migliore per iniziare se non <strong>con la cucina e il vino italiani<\/strong>.[\/vc_column_text][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;default_arrow&#8221; text=&#8221;Scopri di pi\u00f9&#8221; url=&#8221;https:\/\/www.centrostuditaliani.org\/corsi\/cibo-e-vino\/&#8221; margin_top=&#8221;24px&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;662&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;60vh&#8221; custom_height_phone=&#8221;400px&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;56px&#8221; bottom_padding=&#8221;80px&#8221; left_padding_desktop=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5%&#8221; top_padding_tablet=&#8221;56px&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;56px&#8221; top_padding_phone=&#8221;56px&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;56px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-lg-6 vc_col-md-6&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;h3-green&#8221;]\n<h3><span class=\"ez-toc-section\" id=\"Scopri_lItalia\"><\/span>Scopri l&#8217;Italia<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Vogliamo garantire che i nostri studenti vivano il vero cuore dell\u2019Italia. L\u2019apprendimento della lingua prospera quando \u00e8 s<strong>trettamente legato all\u2019immersione culturale<\/strong>, e questo significa esplorare tutto ci\u00f2 che rende autentica l\u2019Italia.[\/vc_column_text][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;default_arrow&#8221; text=&#8221;Scopri di pi\u00f9&#8221; url=&#8221;https:\/\/www.centrostuditaliani.org\/corsi\/vera-italia\/&#8221; margin_top=&#8221;24px&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin_tablet=&#8221;56px&#8221; top_margin_phone=&#8221;56px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;right&#8221; tablet_text_alignment=&#8221;left&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-lg-offset-1 vc_col-lg-5 vc_col-md-offset-1 vc_col-md-5&#8243;][image_with_animation image_url=&#8221;4551&#8243; image_size=&#8221;regular&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;15px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; bg_color=&#8221;#f6f6f6&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;80px&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;80px&#8221; left_padding_desktop=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5%&#8221; top_padding_tablet=&#8221;56px&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;56px&#8221; top_padding_phone=&#8221;56px&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;56px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin_tablet=&#8221;56px&#8221; top_margin_phone=&#8221;56px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;left&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-lg-offset-0 vc_col-lg-5 vc_col-md-offset-0 vc_col-md-5&#8243;][image_with_animation image_url=&#8221;4419&#8243; image_size=&#8221;regular&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;15px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-lg-offset-1 vc_col-lg-6 vc_col-md-offset-1 vc_col-md-6 vc_col-sm-offset-0&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;h3-green&#8221;]\n<h3><span class=\"ez-toc-section\" id=\"Goditi_la_musica\"><\/span>Goditi la musica<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Per noi, imparare una lingua significa immergersi nella cultura, e cosa pu\u00f2 essere pi\u00f9 coinvolgente della <strong>profonda emozione della musica lirica<\/strong>?[\/vc_column_text][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;default_arrow&#8221; text=&#8221;Scopri di pi\u00f9&#8221; url=&#8221;https:\/\/www.centrostuditaliani.org\/corsi\/musica\/&#8221; margin_top=&#8221;24px&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;80px&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;80px&#8221; left_padding_desktop=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5%&#8221; top_padding_tablet=&#8221;56px&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;56px&#8221; top_padding_phone=&#8221;56px&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;56px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin_tablet=&#8221;40px&#8221; top_margin_phone=&#8221;40px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-lg-6 vc_col-md-6&#8243;][image_with_animation image_url=&#8221;2929&#8243; image_size=&#8221;large&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][vc_column column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-lg-offset-1 vc_col-lg-4 vc_col-md-offset-1 vc_col-md-4&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2><span class=\"ez-toc-section\" id=\"In_quali_citta_puoi_imparare_litaliano\"><\/span>In quali citt\u00e0 puoi imparare l&#8217;italiano?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Per vivere le tue esperienze in Italia, puoi visitarci in tre sedi: <strong>Genova, Milano e Urbania<\/strong>. Nelle nostre scuole potrai seguire esperienze ancora pi\u00f9 personalizzate dedicate all\u2019apprendimento della lingua italiana in Italia![\/vc_column_text][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;default_arrow&#8221; text=&#8221;Locations&#8221; url=&#8221;https:\/\/www.centrostuditaliani.org\/it\/sedi\/&#8221; margin_top=&#8221;24px&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;56px&#8221; bottom_padding_tablet=&#8221;32px&#8221; bottom_padding_phone=&#8221;32px&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#202020&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner top_padding_desktop=&#8221;30%&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;30%&#8221; constrain_group_101=&#8221;yes&#8221; top_padding_tablet=&#8221;15%&#8221; constrain_group_102=&#8221;yes&#8221; bottom_padding_tablet=&#8221;15%&#8221; left_padding_tablet=&#8221;5%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;5%&#8221; top_padding_phone=&#8221;15%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;15%&#8221; left_padding_phone=&#8221;5%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-lg-offset-1 vc_col-lg-8 vc_col-md-offset-1 vc_col-md-10&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3><span class=\"ez-toc-section\" id=\"Hai_bisogno_di_prepararti_per_un_esame_Scopri_i_nostri_corsi\"><\/span>Hai bisogno di prepararti per un <span style=\"color: #41bf70;\">esame<\/span>? Scopri i nostri corsi!<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Oltre a vivere la cultura italiana, desideri anche sostenere un esame per il CELI o il CILS? Siamo qui per aiutarti! Scopri i nostri corsi in presenza e approfitta della tua permanenza in Italia per arricchire il tuo curriculum accademico![\/vc_column_text][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;default_arrow&#8221; text=&#8221;Scopri di pi\u00f9&#8221; url=&#8221;https:\/\/www.centrostuditaliani.org\/it\/il-centro-d-esame\/&#8221; margin_top=&#8221;24px&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;3190&#8243; background_image_position=&#8221;center center&#8221; background_image_stacking=&#8221;default&#8221; background_image_loading=&#8221;default&#8221; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_raw_html css=&#8221;&#8221;]JTNDYXNpZGUlM0U=[\/vc_raw_html][nectar_global_section id=&#8221;352&#8243;][nectar_global_section id=&#8221;356&#8243;][vc_raw_html css=&#8221;&#8221;]JTNDJTJGYXNpZGUlM0U=[\/vc_raw_html][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;647&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; color_overlay=&#8221;rgba(0,0,0,0.6)&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column top_padding_desktop=&#8221;32%&#8221; constrain_group_100=&#8221;yes&#8221;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-45","page","type-page","status-publish"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.centrostuditaliani.org\/it\/wp-json\/wp\/v2\/pages\/45","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.centrostuditaliani.org\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.centrostuditaliani.org\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.centrostuditaliani.org\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.centrostuditaliani.org\/it\/wp-json\/wp\/v2\/comments?post=45"}],"version-history":[{"count":34,"href":"https:\/\/www.centrostuditaliani.org\/it\/wp-json\/wp\/v2\/pages\/45\/revisions"}],"predecessor-version":[{"id":5390,"href":"https:\/\/www.centrostuditaliani.org\/it\/wp-json\/wp\/v2\/pages\/45\/revisions\/5390"}],"wp:attachment":[{"href":"https:\/\/www.centrostuditaliani.org\/it\/wp-json\/wp\/v2\/media?parent=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}